{"id":4428,"date":"2019-11-25T17:19:03","date_gmt":"2019-11-25T20:19:03","guid":{"rendered":"http:\/\/ubuntu18-level\/hotelregis.com.ar\/?page_id=4428"},"modified":"2022-11-03T16:11:47","modified_gmt":"2022-11-03T19:11:47","slug":"inicio-pt","status":"publish","type":"page","link":"https:\/\/hotelelcabildo.com\/index.php\/pt\/inicio-pt\/","title":{"rendered":"In\u00edcio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4428\" class=\"elementor elementor-4428\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-397eec7 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"397eec7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9318378\" data-id=\"9318378\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a9c930 elementor-widget elementor-widget-shortcode\" data-id=\"2a9c930\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\n\t\t\t<!-- START Slider Inicio PT REVOLUTION SLIDER 6.1.3 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_10_1_wrapper\" data-source=\"gallery\" style=\"background:#0c0c0c;padding:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_10_1\" style=\"display:none;\" data-version=\"6.1.3\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-26\" data-title=\"Slider 1\" data-thumb=\"\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/El-Cabildo-Lobby-1-100x50.jpg\" data-anim=\"ei:d;eo:d;s:900;r:0;t:fade;sl:7;\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" src=\"\/\/hotelelcabildo.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Hotel El Cabildo - Slide1\" title=\"Hotel El Cabildo &#8211; Slide1\" width=\"2592\" height=\"1944\" data-lazyload=\"\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/El-Cabildo-Lobby-1.jpg\" data-panzoom=\"d:16000;ss:100;se:100;\" class=\"rev-slidebg\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-10-slide-26-layer-2\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/booking.roomcloud.net\/be\/se1\/hotel.jsp?hotel=11713&curr=USD&lang=pt&d=3\" target=\"_blank\" rel=\"nofollow\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ffffff||#ffffff||#ffffff||rgba(252,252,252,1)\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#8e8e93;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-54px,-54px,-54px,0;y:m;yo:-3px,-3px,-3px,70px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal,normal,normal,nowrap;s:30,30,30,24;l:50,50,50,30;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:450px,450px,450px,auto;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#ffffff;bow:2px,2px,2px,2px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:right;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power3.easeOut;st:1530;sp:1500;sR:1530;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"x:left;tp:600;st:w;sp:90;sR:5970;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgba(30,190,165,0.6);font-family:'Lucida Sans Unicode', 'Lucida Grande', sans-serif;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>reservando em nosso site \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-10-slide-26-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ffffff||#ffffff||#ffffff||rgba(252,252,252,1)\"\n\t\t\t\t\t\t\t\tdata-bsh=\"c:#8e8e93;\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-53px,-53px,-53px,0;y:m;yo:-61px,-61px,-61px,-49px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal,normal,normal,nowrap;s:50,50,50,24;l:50,50,50,30;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:455px,455px,455px,auto;h:59px,59px,59px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:right;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power3.easeOut;st:900;sp:1500;sR:900;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"x:left;tp:600;st:w;sp:90;sR:6600;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;font-family:Crimson Text;font-style:italic;\"\n\t\t\t\t\t\t\t>Melhor pre\u00e7o garantido \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-28\" data-title=\"Slider 3\" data-thumb=\"\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/P1019785-100x50.jpg\" data-anim=\"ei:d;eo:d;s:900;r:0;t:fade;sl:7;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/hotelelcabildo.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"Hotel El Cabildo - Slide3\" title=\"Hotel El Cabildo &#8211; Slide3\" width=\"3200\" height=\"2400\" data-lazyload=\"\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/P1019785.jpg\" data-panzoom=\"d:16000;ss:100;se:100;\" class=\"rev-slidebg\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><a\n\t\t\t\t\t\t\t\tid=\"slider-10-slide-28-layer-3\" \n\t\t\t\t\t\t\t\tclass=\"rs-layer\"\n\t\t\t\t\t\t\t\thref=\"https:\/\/booking.roomcloud.net\/be\/se1\/hotel.jsp?hotel=11713&curr=USD&lang=pt&d=3\" target=\"_blank\" rel=\"nofollow\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ffffff||#ffffff||#ffffff||rgba(252,252,252,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:8px,8px,8px,84px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap,nowrap,nowrap,nowrap;s:30,30,30,24;l:50,50,50,30;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:544px,544px,544px,auto;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:5;r:5;b:5;l:5;\"\n\t\t\t\t\t\t\t\tdata-border=\"bos:solid;boc:#ffffff;bow:2px,2px,2px,2px;bor:2px,2px,2px,2px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:51px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power2.easeInOut;st:900;sp:1500;sR:900;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:-51px;o:0;tp:600;e:nothing;st:w;sp:90;sR:6600;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;background-color:rgba(30,190,165,0.5);font-family:'Lucida Sans Unicode', 'Lucida Grande', sans-serif;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>Fique na Hotel EL Cabildo \n\t\t\t\t\t\t\t<\/a><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-10-slide-28-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"#ffffff||#ffffff||#ffffff||rgba(252,252,252,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;y:m;yo:-67px,-67px,-67px,-46px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:nowrap,nowrap,nowrap,nowrap;s:50,50,50,24;l:40,40,40,30;a:center;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:541px,541px,541px,auto;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:51px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power2.easeInOut;st:1340;sp:1500;sR:1340;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:-51px;o:0;tp:600;e:nothing;st:w;sp:90;sR:6160;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:6;font-family:Crimson Text;font-style:italic;\"\n\t\t\t\t\t\t\t>Aproveite Buenos Aires \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t\t<rs-progress class=\"rs-bottom\" style=\"visibility: hidden !important;\"><\/rs-progress>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_10_1',rl:[1240,1024,778,480],el:[600,600,500,400],gw:[1240,1024,778,480],gh:[600,600,500,400],layout:'fullscreen',offsetContainer:'',offset:'50px',mh:\"0\"});\n\t\t\t\t\tvar\trevapi10,\n\t\t\t\t\t\ttpj;\n\t\t\t\t\tjQuery(function() {\n\t\t\t\t\t\ttpj = jQuery;\n\t\t\t\t\t\tif(tpj(\"#rev_slider_10_1\").revolution == undefined){\n\t\t\t\t\t\t\trevslider_showDoubleJqueryError(\"#rev_slider_10_1\");\n\t\t\t\t\t\t}else{\n\t\t\t\t\t\t\trevapi10 = tpj(\"#rev_slider_10_1\").show().revolution({\n\t\t\t\t\t\t\t\tjsFileLocation:\"\/\/hotelelcabildo.com\/wp-content\/plugins\/revslider\/public\/assets\/js\/\",\n\t\t\t\t\t\t\t\tsliderLayout:\"fullscreen\",\n\t\t\t\t\t\t\t\tvisibilityLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tgridwidth:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tgridheight:\"600,600,500,400\",\n\t\t\t\t\t\t\t\tminHeight:\"\",\n\t\t\t\t\t\t\t\tlazyType:\"smart\",\n\t\t\t\t\t\t\t\tspinner:\"spinner0\",\n\t\t\t\t\t\t\t\teditorheight:\"600,600,500,400\",\n\t\t\t\t\t\t\t\tresponsiveLevels:\"1240,1024,778,480\",\n\t\t\t\t\t\t\t\tdisableForceFullWidth:true,\n\t\t\t\t\t\t\t\tfullScreenOffset:\"50px\",\n\t\t\t\t\t\t\t\tdisableProgressBar:\"on\",\n\t\t\t\t\t\t\t\tnavigation: {\n\t\t\t\t\t\t\t\t\tmouseScrollNavigation:false,\n\t\t\t\t\t\t\t\t\tonHoverStop:false,\n\t\t\t\t\t\t\t\t\ttouch: {\n\t\t\t\t\t\t\t\t\t\ttouchenabled:true,\n\t\t\t\t\t\t\t\t\t\tswipe_min_touches:50\n\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\tarrows: {\n\t\t\t\t\t\t\t\t\t\tenable:true,\n\t\t\t\t\t\t\t\t\t\tstyle:1010,\n\t\t\t\t\t\t\t\t\t\tleft: {\n\t\t\t\t\t\t\t\t\t\t\th_offset:30\n\t\t\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\t\t\tright: {\n\t\t\t\t\t\t\t\t\t\t\th_offset:30\n\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tviewPort: {\n\t\t\t\t\t\t\t\t\tenable:true,\n\t\t\t\t\t\t\t\t\tvisible_area:\"20%\"\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tfallbacks: {\n\t\t\t\t\t\t\t\t\tnextSlideOnWindowFocus:true,\n\t\t\t\t\t\t\t\t\tallowHTML5AutoPlayOnAndroid:true\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\n\t\t\t\t\t});\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a2de1a5 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"a2de1a5\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97b6498\" data-id=\"97b6498\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f7bd16 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9f7bd16\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;2&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08a7721 elementor-section-stretched elementor-section-full_width elementor-hidden-desktop elementor-section-height-default elementor-section-height-default\" data-id=\"08a7721\" data-element_type=\"section\" id=\"socialnetworks\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-01074a0\" data-id=\"01074a0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-147162b elementor-widget elementor-widget-text-editor\" data-id=\"147162b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3 style=\"text-align: center;\"><a href=\"https:\/\/hotelelcabildo.book-onlinenow.net\/index.aspx?lan_id=es-ES\" target=\"_blank\" rel=\"noopener\">Reservas<\/a><\/h3>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58b9fa9\" data-id=\"58b9fa9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09e4448 elementor-widget elementor-widget-text-editor\" data-id=\"09e4448\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div style=\"font-size: 16px; text-align: center;\"><a href=\"https:\/\/api.whatsapp.com\/send?phone=5491151764304\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" title=\"WhatsApp Hotel El Cabildo\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/09\/whatsapp.png\" alt=\"WhatsApp Hotel El Cabildo\" width=\"20px\" \/><\/a><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1b8f13 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"d1b8f13\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3383648\" data-id=\"3383648\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c8e1f9 elementor-widget elementor-widget-thim-heading\" data-id=\"2c8e1f9\" data-element_type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sc-heading article_heading wrapper-line-heading\"><h3 class=\"heading__primary\">Nossos Quartos<\/h3><p class=\"heading__secondary\">Quartos espa\u00e7osos que tornar\u00e3o sua estadia no cora\u00e7\u00e3o de Buenos Aires mais agrad\u00e1vel.<br>Totalmente equipados com cofre, frigobar, ar condicionado \/ aquecimento central, banheiro com banheira e secador de cabelo, telefone, TV a cabo, Internet wi-fi, janelas com vidros duplos e cortinas opacas.<\/p><span class=\"line-heading\"><span><\/span><\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49eaed6 elementor-widget elementor-widget-thim-hotel-room\" data-id=\"49eaed6\" data-element_type=\"widget\" data-widget_type=\"thim-hotel-room.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<div id=\"hotel_booking_slider_6a0465493ccbc\" class=\"hb_room_carousel_container tp-hotel-booking\">\n\t<!--navigation-->\n\t\t\t<div class=\"navigation owl-buttons\">\n\t\t\t<div class=\"prev\"><span class=\"pe-7s-angle-left\"><\/span><\/div>\n\t\t\t<div class=\"next\"><span class=\"pe-7s-angle-right\"><\/span><\/div>\n\t\t<\/div>\n\t\n\t<!--text_link-->\n\t\t\t<div class=\"text_link\">\n\t\t\t<a target=\"_self\" href=\"http:\/\/hotelelcabildo.com\/index.php\/pt\/quartos\/\">Ver Todos os Quartos<\/a>\n\t\t<\/div>\n\t\n\t<div id=\"hotel_booking_slider_6a0465493ccbc\" class=\"hb_room_carousel_container tp-hotel-booking\">\n\t\t<div class=\"hb_room_carousel\">\n\t\t\t<ul class=\"rooms owl-carousel tp-hotel-booking hb-catalog-column-4\">\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-5594\" class=\"post-5594 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-estandard\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/P1015521-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo \u2013 Habitaci\u00f3n Suite\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/suite-con-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/suite-con-jacuzzi\/\">Suite<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/room-type\/estandard\/\" rel=\"tag\">Est\u00e1ndard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>C\u00f3moda y amplia habitaci\u00f3n<\/p>\r\n<p><i>* Precios expresados en USD *<\/i><\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;29,70<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/suite-con-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-5632\" class=\"post-5632 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-standard-pt\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/P1015521-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo \u2013 Quarto Suite\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/suite-com-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/suite-com-jacuzzi\/\">Suite<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room-type\/standard-pt\/\" rel=\"tag\">Standard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>Quarto confort\u00e1vel e espa\u00e7oso.<\/p>\r\n<p> <i> * Pre\u00e7os expressos em d\u00f3lares * <\/i> <\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;29,70<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/suite-com-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-5629\" class=\"post-5629 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-standard\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/P1015521-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo \u2013 Suite Room\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/suite-with-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/suite-with-jacuzzi\/\">Suite<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room-type\/standard\/\" rel=\"tag\">Standard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>Comfortable and spacious room.<\/p>\r\n<p> <i> * Prices expressed in USD * <\/i> <\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;29,70<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/suite-with-jacuzzi\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-4480\" class=\"post-4480 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-standard-pt\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/05.Matrimonial-Std-El-Cabildo-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo - Quarto duplo\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/duplo\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/duplo\/\">Duplo<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room-type\/standard-pt\/\" rel=\"tag\">Standard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>Quarto confort\u00e1vel e espa\u00e7oso para receber at\u00e9 2 pessoas.<\/p>\r\n<p> <i> * Pre\u00e7os expressos em d\u00f3lares * <\/i> <\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;17,60<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/pt\/room\/duplo\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-4478\" class=\"post-4478 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-standard\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/05.Matrimonial-Std-El-Cabildo-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo - Double room\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/double\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/double\/\">Double<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room-type\/standard\/\" rel=\"tag\">Standard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>Comfortable and spacious room to host up to 2 adults.<\/p>\r\n<p> <i> * Prices expressed in USD * <\/i> <\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;17,60<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/en\/room\/double\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\n\t\t\t\t\t<li id=\"room-1986\" class=\"post-1986 hb_room type-hb_room status-publish has-post-thumbnail hentry hb_room_type-estandard\">\n\n\t\t\t\t\t\t\n\t\t\t\t\t\t<div class=\"summary entry-summary\">\n\n\t\t\t\t\t\t\t\n<div class=\"media\">\n\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/05.Matrimonial-Std-El-Cabildo-270x270.jpg\" width=\"270\" height=\"270\" alt=\"Hotel El Cabildo - Habitaci\u00f3n Doble\"\/>\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/doble\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t\t<div class=\"content-room\">\n\t\t\t\t\t\t\t\t<div class=\"title-room\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"title\">\n\t<h4>\n\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/doble\/\">Doble<\/a>\n\t<\/h4>\n<\/div>\n<div class=\"room-types\"><a href=\"https:\/\/hotelelcabildo.com\/index.php\/room-type\/estandard\/\" rel=\"tag\">Est\u00e1ndard<\/a><\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\"><p>C\u00f3moda y amplia habitaci\u00f3n para recibir hasta 2 personas.<\/p>\r\n<p><i>* Precios expresados en USD *<\/i><\/p>\r\n<div class=\"information_services\">\r\n\t<ul>\r\n\t\t<li><i class=\"fa fa-coffee\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-wifi\"><\/i><\/li>\r\n\t\t<li><i class=\"fa fa-television\"><\/i><\/li>\r\n\t<\/ul>\r\n<\/div><\/div>\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\n<div class=\"footer-content-room\">\n\t\n\t\t<div class=\"price\">\n\t\t\t<span class=\"title-price\">Desde<\/span>\n\n\t\t\t\t\t\t\t<span class=\"price_value price_min\">\n\t            &#36;17,60<span class=\"unit\">persona\/noche<\/span>\n            <\/span>\n\t\t\t\n\t\t<\/div>\n\t\n\t<div class=\"actions\">\n\t\t<div class=\"action-btn\">\n\t\t\t<a href=\"https:\/\/hotelelcabildo.com\/index.php\/room\/doble\/\" class=\"button readmore\">\n\t\t\t\tM\u00e1s Info...\t\t\t<\/a>\n\t\t<\/div>\n\t<\/div>\n<\/div>\t\t\t\t\t\t<\/div><!-- .summary -->\n\n\t\t\t\t\t\t\n\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t<\/ul>\n\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<script type=\"text\/javascript\">\n\t(function ($) {\n\t\t\"use strict\";\n\t\t$(document).ready(function () {\n\t\t\tvar thimpress_hotel_booking_carousel = $('#hotel_booking_slider_6a0465493ccbc .hb_room_carousel .rooms');\n\t\t\tthimpress_hotel_booking_carousel.owlCarousel({\n\t\t\t\tnav               : false,\n\t\t\t\tdots              : false,\n\t\t\t\titems             : 4,\n\t\t\t\tdotsSpeed         : 600,\n\t\t\t\tsmartSpeed        : 600,\n\t\t\t\tautoplay          : true,\n\t\t\t\tautoplayHoverPause: true,\n\t\t\t\tloop              : true,\n\t\t\t\tresponsive        : {\n\t\t\t\t\t\/\/ breakpoint from 0 up\n\t\t\t\t\t0   : {\n\t\t\t\t\t\titems: 1\n\t\t\t\t\t},\n\t\t\t\t\t\/\/ breakpoint from 480 up\n\t\t\t\t\t480 : {\n\t\t\t\t\t\titems: 1\n\t\t\t\t\t},\n\t\t\t\t\t\/\/ breakpoint from 768 up\n\t\t\t\t\t768 : {\n\t\t\t\t\t\titems: 2\n\t\t\t\t\t},\n\t\t\t\t\t\/\/ breakpoint from 1024 up\n\t\t\t\t\t1024: {\n\t\t\t\t\t\titems: 4\t\t\t\t\t}\n\t\t\t\t}\n\t\t\t});\n\t\t\t\/\/ next\n\t\t\t$('#hotel_booking_slider_6a0465493ccbc .navigation .next').click(function () {\n\t\t\t\tthimpress_hotel_booking_carousel.trigger('next.owl.carousel');\n\t\t\t});\n\t\t\t\/\/ prev\n\t\t\t$('#hotel_booking_slider_6a0465493ccbc .navigation .prev').click(function () {\n\t\t\t\tthimpress_hotel_booking_carousel.trigger('prev.owl.carousel');\n\t\t\t});\n\t\t});\n\t})(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21807fe elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"21807fe\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e441661\" data-id=\"e441661\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2539efc elementor-widget elementor-widget-html\" data-id=\"2539efc\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sale-off banner-round\">\r\n\t<p class=\"title\">\r\nDesfrute de Buenos Aires<br>Fique em<\/p>\r\n\t<p class=\"h1\">El Cabildo<br>Hotel<\/p>\r\n\t<p class=\"off\"><\/p>\r\n\t<p class=\"learn-more\"><a href=\"http:\/\/hotelelcabildo.com\/index.php\/pt\/quartos\/\">Saber mais<\/a><\/p>\r\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4fd9926 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4fd9926\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5853e5c\" data-id=\"5853e5c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fc7fab elementor-widget elementor-widget-thim-heading\" data-id=\"4fc7fab\" data-element_type=\"widget\" data-widget_type=\"thim-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"sc-heading article_heading wrapper-line-heading\"><h3 class=\"heading__primary\"> Nossos Servi\u00e7os<\/h3><p class=\"heading__secondary\">Regis oferece uma ampla gama de servi\u00e7os para tornar a melhor estadia na cidade.<\/p><span class=\"line-heading\"><span><\/span><\/span><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6184d5d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6184d5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b92fcf8\" data-id=\"b92fcf8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48119ee elementor-widget elementor-widget-thim-icon-box\" data-id=\"48119ee\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 70px;height: 70px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/reception-bell.png\" alt=\"Recep\u00e7\u00e3o\" title=\"Recep\u00e7\u00e3o\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Recep\u00e7\u00e3o <\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">\nRecep\u00e7\u00e3o 24 horas para seu conforto e tranquilidade<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-b759a86\" data-id=\"b759a86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-078094a elementor-widget elementor-widget-thim-icon-box\" data-id=\"078094a\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 70px;height: 70px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/wifi.png\" alt=\"Internet Wi-Fi\" title=\"Internet Wi-Fi\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Wi-fi e Fax<\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">Acesso \u00e0 Internet Wi-Fi e Servi\u00e7o de fax<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-428aad0\" data-id=\"428aad0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e08052 elementor-widget elementor-widget-thim-icon-box\" data-id=\"1e08052\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 80px;height: 80px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/pase-microcentro.png\" alt=\"Passagem de ve\u00edculos para o microcentro\" title=\"Passagem de ve\u00edculos para o microcentro\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Passe para ve\u00edculos<\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">Passe para o microcentro para ve\u00edculos<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-d0ac1fb\" data-id=\"d0ac1fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb1cea9 elementor-widget elementor-widget-thim-icon-box\" data-id=\"cb1cea9\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 70px;height: 70px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/concierge.png\" alt=\"Concierge\" title=\"Concierge\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Concierge<\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">Servi\u00e7os de concierge 24 horas<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-5917b87\" data-id=\"5917b87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f47f2d7 elementor-widget elementor-widget-thim-icon-box\" data-id=\"f47f2d7\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 70px;height: 70px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/coffe-cup-1-e1590794748811.png\" alt=\"Caf\u00e9 da manh\u00e3 continental\" title=\"Caf\u00e9 da manh\u00e3 continental\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Caf\u00e9 da Manh\u00e3 Continental<\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">Ampla variedade de op\u00e7\u00f5es ricas e nutritivas para come\u00e7ar o dia<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-16 elementor-top-column elementor-element elementor-element-862c9ea\" data-id=\"862c9ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b270c5 elementor-widget elementor-widget-thim-icon-box\" data-id=\"6b270c5\" data-element_type=\"widget\" data-widget_type=\"thim-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"inner-box auto-hidden\"><div  class=\"wrapper-box-icon has_custom_image text-center  \" ><div class=\"smicon-box iconbox-top\"><div class=\"boxes-icon\" style=\"width: 70px;height: 70px;\"><span class=\"inner-icon\"><span class=\"icon icon-images\"><img decoding=\"async\" src=\"https:\/\/hotelelcabildo.com\/wp-content\/uploads\/2020\/04\/parking.png\" alt=\"Estacionamento\" title=\"Estacionamento\" ><\/span><\/span><\/div><div class=\"content-inner\" ><div class=\"sc-heading article_heading\"><h3 class = \"heading__primary\" >Estacionamento<\/h3><\/div><div class=\"desc-icon-box\"><div style=\"font-weight: normal;\">N\u00e3o temos nossas pr\u00f3prias instala\u00e7\u00f5es de estacionamento. Estacionamento nas proximidades<\/div><\/div><\/div><\/div><!--end smicon-box--><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f42cbfe elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f42cbfe\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6f408f\" data-id=\"c6f408f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75da427 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"75da427\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3580cc0\" data-id=\"3580cc0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecf5e02 elementor-widget elementor-widget-html\" data-id=\"ecf5e02\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<a class=\"twitter-timeline\" href=\"https:\/\/twitter.com\/DisfrutemosBA?ref_src=twsrc%5Etfw\" data-height=\"600\">Eventos BA DisfrutemosBA<\/a> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-7cc4fff\" data-id=\"7cc4fff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c7469d elementor-widget elementor-widget-thim-testimonials\" data-id=\"8c7469d\" data-element_type=\"widget\" data-widget_type=\"thim-testimonials.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"widget-box-title\"><h3 class=\"widget-title\">Testemunhos<\/h3><\/div><div class=\"sc-testimonials owl-carousel\" data-time=\"10000\"><div class=\"item_testimonial\"><div class=\"testimonial_content\"><strong>Boa rela\u00e7\u00e3o custo-benef\u00edcio<\/strong>\r\n\r\n<em>Para destacar a limpeza: tudo impec\u00e1vel.\r\nA localiza\u00e7\u00e3o \u00e9 muito boa, perto das principais linhas de metr\u00f4 e do Metrobus. O quarto estava pronto no hor\u00e1rio combinado, nos instalamos bem nos dias em que ficamos. A aten\u00e7\u00e3o da equipe \u00e9 muito boa. O caf\u00e9 da manh\u00e3 fica em um caf\u00e9 a meia quadra do hotel e \u00e9 muito bom.\r\nEm resumo, eu o recomendo e retornaria em uma pr\u00f3xima visita. (Jul., 2019)<\/em><\/div><div class=\"testimonial-footer\"><div class=\"title-regency\"><h6>  Gustavo &#8211; San Luis, Argentina  <\/h6><\/div><\/div><\/div><div class=\"item_testimonial\"><div class=\"testimonial_content\"><strong>Como em casa<\/strong>\r\n\r\n<em>\"Lugar confort\u00e1vel, funcion\u00e1rios atenciosos, \u00e9 barato, bem cuidado e bem localizado, voc\u00ea sai do barco a alguns quarteir\u00f5es e pronto. Voc\u00ea pode ir ao centro, teatros, bares de l\u00e1 todos a p\u00e9. Que mais!\" (Jun., 2019)<\/em><\/div><div class=\"testimonial-footer\"><div class=\"title-regency\"><h6>  Elisa  <\/h6><\/div><\/div><\/div><div class=\"item_testimonial\"><div class=\"testimonial_content\"><strong>\u00d3tima localiza\u00e7\u00e3o<\/strong>\r\n\r\n<em>\"Hotel confort\u00e1vel e limpo, com uma localiza\u00e7\u00e3o imbat\u00edvel. Funcion\u00e1rios calorosos e muito prestativos. Voc\u00ea pode ir a p\u00e9 do porto para evitar um custo de transfer\u00eancia se viajar de barco. Localizado no micro-centro e a um passo de lugares muito tur\u00edsticos.\" (Oct., 2019)<\/em><\/div><div class=\"testimonial-footer\"><div class=\"title-regency\"><h6>  Laura &#8211;  Montevid\u00e9u, Uruguai  <\/h6><\/div><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00d3tima localiza\u00e7\u00e3o<br \/>\n&#8220;Hotel confort\u00e1vel e limpo, com uma localiza\u00e7\u00e3o imbat\u00edvel. Funcion\u00e1rios calorosos e muito prestativos. Voc\u00ea pode ir a p\u00e9 do porto para evitar um custo de transfer\u00eancia se viajar de barco. Localizado no micro-centro e a um passo de lugares muito tur\u00edsticos.&#8221; (Oct., 2019)<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/homepage.php","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-4428","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/pages\/4428"}],"collection":[{"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/comments?post=4428"}],"version-history":[{"count":0,"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/pages\/4428\/revisions"}],"wp:attachment":[{"href":"https:\/\/hotelelcabildo.com\/index.php\/wp-json\/wp\/v2\/media?parent=4428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}